{"id":3912,"date":"2026-08-12T06:19:25","date_gmt":"2026-08-12T06:19:25","guid":{"rendered":"https:\/\/cnbeerequipment.com\/?p=3912"},"modified":"2026-08-12T06:19:25","modified_gmt":"2026-08-12T06:19:25","slug":"specifiche-tecniche-ingombro-e-calcolo-dei-lotti-di-un-impianto-di-produzione-di-birra-da-3-bbl","status":"publish","type":"post","link":"https:\/\/cnbeerequipment.com\/it\/3-bbl-brewing-system-specs-footprint-and-batch-math\/","title":{"rendered":"Sistema di produzione 3 BBL: specifiche tecniche, ingombro e calcolo dei lotti"},"content":{"rendered":"<p>David Zhang | Fondatore e amministratore delegato, ZPET (Shandong ZhongPi Machinery Equipment Co., Ltd.) | Pubblicato nell'agosto 2026<\/p>\n<p>Un impianto di produzione da 3 BBL ha una capacit\u00e0 di 352 L per lotto. La sala di cottura occupa circa 2 m\u00b2, ma il birrificio operativo richiede 45\u201360 m\u00b2 e un\u2019altezza del soffitto di 3 m. La produzione settimanale \u00e8 compresa tra 6 e 13 BBL a seconda del numero di fermentatori e del tempo di rotazione delle cisterne, non della capacit\u00e0 della sala di cottura.<\/p>\n<figure id=\"attachment_3913\" aria-describedby=\"caption-attachment-3913\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-3913 size-full\" src=\"https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/08\/Microbrewery-Equipment-1.webp\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/08\/Microbrewery-Equipment-1.webp 600w, https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/08\/Microbrewery-Equipment-1-300x200.webp 300w, https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/08\/Microbrewery-Equipment-1-18x12.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-3913\" class=\"wp-caption-text\">Sistema di produzione 3 BBL: specifiche tecniche, ingombro e calcolo dei lotti<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2><strong><b>I numeri dietro l'etichetta<\/b><\/strong><\/h2>\n<p>Le indicazioni relative alle taglie in questa categoria sono approssimative, e le differenze tra una taglia e l\u2019altra sono pi\u00f9 significative di quanto possa sembrare.<\/p>\n<table style=\"height: 265px;\" width=\"1292\">\n<tbody>\n<tr>\n<td><strong><b>Etichetta di sistema<\/b><\/strong><\/td>\n<td><strong><b>Volume di lavoro per lotto<\/b><\/strong><\/td>\n<td><strong><b>Fusti da mezzo barile per lotto<\/b><\/strong><\/td>\n<td><strong><b>Pinte statunitensi (16 oz) per lotto<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>2 BBL<\/td>\n<td>235 L<\/td>\n<td>4.0<\/td>\n<td>496<\/td>\n<\/tr>\n<tr>\n<td>2,5 BBL<\/td>\n<td>293 L<\/td>\n<td>5.0<\/td>\n<td>620<\/td>\n<\/tr>\n<tr>\n<td>3 BBL<\/td>\n<td>352 L<\/td>\n<td>6.0<\/td>\n<td>744<\/td>\n<\/tr>\n<tr>\n<td>3,5 BBL<\/td>\n<td>411 L<\/td>\n<td>7.0<\/td>\n<td>868<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>Base di calcolo: 1 barile di birra statunitense = 117,3 L. Un fusto da mezzo barile = 58,67 L. Una pinta da 16 oz = 0,473 L. I dati si riferiscono ai volumi del birrificio al lordo delle perdite; si prevede una perdita totale compresa tra 5 e 101 TP3T tra la fase di separazione e il fusto, dovuta a sedimenti, lievito e trasferimento.<\/em><\/p>\n<p>Moving from 2 BBL to 3.5 BBL adds three kegs per batch, or 75% more beer for a vessel diameter increase of roughly 15 cm. That asymmetry is the core argument for buying at the top of this range rather than the bottom, and it is why &#8220;2 BBL is cheaper&#8221; is a weak basis for the decision.<\/p>\n<p>Note also that a &#8220;3 BBL system&#8221; quoted by two suppliers may mean two different things. Some quote the kettle&#8217;s working volume; some quote the finished wort volume delivered to the fermenter after boil-off. The difference is 6\u201310%. Ask which number you are being given.<\/p>\n<h2><strong><b>Vessel dimensions and how to check a supplier&#8217;s numbers<\/b><\/strong><\/h2>\n<p><a href=\"https:\/\/cnbeerequipment.com\/it\/two-vessel-brewhouse\/\">Dimensioni dell'imbarcazione<\/a> dipende dal volume utile, dallo spazio libero necessario e dal rapporto altezza\/diametro scelto dal costruttore. Due fornitori possono proporre la stessa capacit\u00e0 con una differenza di 40 cm nell'altezza complessiva.<\/p>\n<table style=\"height: 445px;\" width=\"1274\">\n<tbody>\n<tr>\n<td><strong><b>Nave<\/b><\/strong><\/td>\n<td><strong><b>Volume di lavoro.<\/b><\/strong><\/td>\n<td><strong><b>Volume totale del progetto.<\/b><\/strong><\/td>\n<td><strong><b>Diametro tipico<\/b><\/strong><\/td>\n<td><strong><b>Altezza del lato dritto<\/b><\/strong><\/td>\n<td><strong><b>Altezza totale, gambe incluse<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>2 tini di ammostamento\/filtrazione da 2 BBL<\/td>\n<td>235 L<\/td>\n<td>~295 L<\/td>\n<td>0,80 m<\/td>\n<td>0,59 m<\/td>\n<td>1,55\u20131,75 m<\/td>\n<\/tr>\n<tr>\n<td>Caldaia\/vasca di ricircolo da 2 BBL<\/td>\n<td>235 L<\/td>\n<td>~295 L<\/td>\n<td>0,80 m<\/td>\n<td>0,59 m<\/td>\n<td>1,55\u20131,75 m<\/td>\n<\/tr>\n<tr>\n<td>3 tini di ammostamento\/filtrazione BBL<\/td>\n<td>352 L<\/td>\n<td>~440 L<\/td>\n<td>0,90 m<\/td>\n<td>0,69 m<\/td>\n<td>1,70\u20131,95 m<\/td>\n<\/tr>\n<tr>\n<td>Caldaia\/vasca di agitazione da 3 BBL<\/td>\n<td>352 L<\/td>\n<td>~440 L<\/td>\n<td>0,90 m<\/td>\n<td>0,69 m<\/td>\n<td>1,70\u20131,95 m<\/td>\n<\/tr>\n<tr>\n<td>Caldaia\/vasca di whirlpool da 3,5 BBL<\/td>\n<td>411 L<\/td>\n<td>~515 L<\/td>\n<td>0,95 m<\/td>\n<td>0,73 m<\/td>\n<td>1,75\u20132,00 m<\/td>\n<\/tr>\n<tr>\n<td>Fermentatore da 3 BBL (conico)<\/td>\n<td>352 L<\/td>\n<td>~460 L<\/td>\n<td>0,80 m<\/td>\n<td>0,85 m<\/td>\n<td>2,00\u20132,30 m<\/td>\n<\/tr>\n<tr>\n<td>3 BBL <a href=\"https:\/\/cnbeerequipment.com\/it\/products\/serbatoi-di-birra-luminosi\/\">serbatoio per birra chiara<\/a><\/td>\n<td>352 L<\/td>\n<td>~390 L<\/td>\n<td>0,80 m<\/td>\n<td>0,78 m<\/td>\n<td>1,85\u20132,10 m<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Due controlli che vale la pena effettuare su qualsiasi scheda tecnica che ricevi:<\/p>\n<p><strong>Spazio libero nei fermentatori.<\/strong>\u00a0Un fermentatore con una capacit\u00e0 dichiarata di 352 L totali anzich\u00e9 352 L utili andr\u00e0 in trabocco. Su una scala di 3 BBL, una schiuma vigorosa di birra ale richiede un volume del serbatoio compreso tra 25 e 30%. Se la scheda tecnica riporta un unico valore, chiedete se si tratta della capacit\u00e0 utile o totale.<\/p>\n<p><strong>Altezza complessiva rispetto al percorso di accesso.<\/strong>\u00a0L'altezza totale indicata nella tabella sopra si riferisce alla dimensione in posizione verticale. Lo spazio necessario per la consegna dipende dalla posizione orizzontale del recipiente, ovvero dal diametro pi\u00f9 la base di appoggio, e dalla diagonale necessaria per farlo passare attraverso una porta. Un bollitore con diametro di 0,90 m non passa attraverso una porta di 0,80 m, indipendentemente dall'altezza della stanza.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong><b>Ingombro della sala: perch\u00e9 2 m\u00b2 di serbatoi richiedono 50 m\u00b2 di birrificio<\/b><\/strong><\/h2>\n<p>Sommando le superfici di base dei serbatoi si ottiene un numero privo di significato operativo. Ecco qual \u00e8 il consumo effettivo di un birrificio da 3 BBL con sei fermentatori:<\/p>\n<table style=\"height: 643px;\" width=\"1329\">\n<tbody>\n<tr>\n<td>Zona<\/td>\n<td>Area<\/td>\n<td>Note<\/td>\n<\/tr>\n<tr>\n<td>Serbatoi del reparto di fermentazione (a 2 serbatoi)<\/td>\n<td>1,8\u20132,2 m\u00b2<\/td>\n<td>Due serbatoi, pi\u00f9 una pompa e uno scambiatore di calore su telaio<\/td>\n<\/tr>\n<tr>\n<td>Autorizzazione per l'intervento nel reparto di produzione della birra<\/td>\n<td>8\u201310 m\u00b2<\/td>\n<td>0,9 m come spazio minimo su tre lati; sul lato anteriore sono necessari 1,2 m per la movimentazione dei tubi flessibili e la raschiatura del filtro<\/td>\n<\/tr>\n<tr>\n<td>Fila di fermentatori (6 \u00d7 3 BBL)<\/td>\n<td>5,0\u20135,5 m\u00b2<\/td>\n<td>0,80 m di diametro, 0,15 m di distanza tra i gusci per consentire l'accesso alla struttura di sostegno<\/td>\n<\/tr>\n<tr>\n<td>Corridoio di accesso al fermentatore<\/td>\n<td>8\u201310 m\u00b2<\/td>\n<td>1,5 m di spazio libero davanti per i bracci di travaso, i tubi flessibili e i contenitori per la raccolta del lievito<\/td>\n<\/tr>\n<tr>\n<td>Movimentazione dei cereali e mulino<\/td>\n<td>4\u20136 m\u00b2<\/td>\n<td>Mulino, cassetta per la granella e un pallet di malto pronti per la spedizione<\/td>\n<\/tr>\n<tr>\n<td>Refrigeratore a glicole e collettore<\/td>\n<td>2\u20133 m\u00b2<\/td>\n<td>Se l'installazione avviene all'interno; quella all'esterno libera spazio ma comporta perdite di linea<\/td>\n<\/tr>\n<tr>\n<td>Carrello CIP e stoccaggio dei prodotti chimici<\/td>\n<td>3\u20134 m\u00b2<\/td>\n<td>Il deposito di sostanze chimiche in locali chiusi a chiave \u00e8 solitamente un requisito previsto dalla normativa<\/td>\n<\/tr>\n<tr>\n<td>Lavaggio dei fusti, stoccaggio temporaneo, cella frigorifera<\/td>\n<td>8\u201312 m\u00b2<\/td>\n<td>L'aspetto che pi\u00f9 spesso viene trascurato al momento della firma del contratto di locazione<\/td>\n<\/tr>\n<tr>\n<td>Percorsi di circolazione e drenaggio<\/td>\n<td>5\u20138 m\u00b2<\/td>\n<td>Corridoio con canale di scolo a trincea e percorso pedonale sicuro<\/td>\n<\/tr>\n<tr>\n<td>Totale<\/td>\n<td>45\u201360 m\u00b2<\/td>\n<td>circa 485\u2013645 piedi quadrati<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Un impianto da 2 BBL riduce tale superficie di circa 6\u20139 m\u00b2. Non la dimezza, poich\u00e9 gli spazi liberi, il drenaggio, la movimentazione del grano e la logistica dei fusti sono fattori che non dipendono in modo significativo dalle dimensioni. Questo \u00e8 il secondo motivo per cui l\u2019opzione pi\u00f9 piccola della gamma raramente rappresenta la scelta pi\u00f9 conveniente: in entrambi i casi, si paga comunque la maggior parte del costo dello spazio.<\/p>\n<figure id=\"attachment_3914\" aria-describedby=\"caption-attachment-3914\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-3914 size-full\" src=\"https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/08\/Microbrewery-Equipment-2.webp\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/08\/Microbrewery-Equipment-2.webp 600w, https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/08\/Microbrewery-Equipment-2-300x200.webp 300w, https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/08\/Microbrewery-Equipment-2-18x12.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-3914\" class=\"wp-caption-text\">Sistema di produzione 3 BBL: specifiche tecniche, ingombro e calcolo dei lotti<\/figcaption><\/figure>\n<h3><strong><b>Altezza del soffitto e carico sul pavimento<\/b><\/strong><\/h3>\n<p><strong>Soffitto.<\/strong>\u00a0Take the tallest vessel&#8217;s overall height, add clearance to open the top manway, and add hoist travel if you plan to lift grain or a pump. For a 3 BBL fermenter at 2.30 m overall, 3.0 m is the practical minimum and 3.4 m makes the room workable. Sprinkler heads, ductwork, and lighting all reduce usable height below the structural slab, so measure to the lowest obstruction over each vessel position, not to the ceiling.<\/p>\n<p><strong>Carico sul pavimento.<\/strong>\u00a0Calcolalo, invece di darlo per scontato:<\/p>\n<p>Peso totale del serbatoio \u2248 (volume utile in L \u00d7 1,05 kg\/L) + tara del serbatoio Carico puntuale per gamba = peso totale \u00f7 numero di gambe Carico distribuito = peso totale \u00f7 area della base del serbatoio<\/p>\n<p>Per un fermentatore da 3 BBL, il solo liquido pesa circa 370 kg. Aggiungete il peso della tara, che dovreste richiedere al fornitore anzich\u00e9 stimarlo, e dividete il tutto per circa 0,5 m\u00b2 di superficie di base. Il valore cos\u00ec calcolato si attesta in genere al di sopra dei 1.000 kg\/m\u00b2, valore che rientra nei limiti di carico della maggior parte delle solette in calcestruzzo al piano terra, ma supera quelli di molti pavimenti sospesi. Se il vostro locale non \u00e8 a livello del suolo, fate verificare il valore di carico da un ingegnere strutturale prima di effettuare l\u2019ordine.<\/p>\n<h2><strong><b>Calcoli in blocco: convertire 352 L in un valore settimanale<\/b><\/strong><\/h2>\n<p>Il parametro che determina la produzione \u00e8 la capacit\u00e0 del fermentatore, non quella del salone di cottura. Un salone di cottura da 3 BBL pu\u00f2 essere utilizzato due volte al giorno. Un fermentatore da 3 BBL rimane occupato per un periodo compreso tra 10 e 35 giorni.<\/p>\n<p><strong>lotti a settimana = (numero di fermentatori \u00f7 giorni di ciclo) \u00d7 7<\/strong><\/p>\n<p>I giorni di lavorazione devono includere la fermentazione primaria, il dry hopping o l\u2019affinamento, il raffreddamento rapido e il ciclo CIP. I birrai che considerano solo la fermentazione primaria sovrastimano la propria capacit\u00e0 del 30\u201340%.<\/p>\n<h3><strong><b>3 Produzione del sistema BBL in base al numero di fermentatori e al tempo di ciclo<\/b><\/strong><\/h3>\n<table style=\"height: 297px;\" width=\"1303\">\n<tbody>\n<tr>\n<td><strong><b>Tempo di rotazione<\/b><\/strong><\/td>\n<td><strong><b>4 FV<\/b><\/strong><\/td>\n<td><strong><b>6 FV<\/b><\/strong><\/td>\n<td><strong><b>8 FV<\/b><\/strong><\/td>\n<td><strong><b>10 FV<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>10 giorni (fermentazione rapida, senza affinamento)<\/td>\n<td>8,4 BBL\/settimana<\/td>\n<td>12,6 barili alla settimana<\/td>\n<td>16,8 BBL\/settimana<\/td>\n<td>21,0 BBL\/sett.<\/td>\n<\/tr>\n<tr>\n<td>14 giorni (birra ale standard)<\/td>\n<td>6,0 BBL\/sett.<\/td>\n<td>9,0 BBL\/settimana<\/td>\n<td>12,0 BBL\/sett.<\/td>\n<td>15,0 BBL\/sett.<\/td>\n<\/tr>\n<tr>\n<td>21 giorni (dry-hopping, fermentazione prolungata)<\/td>\n<td>4,0 BBL\/settimana<\/td>\n<td>6,0 BBL\/sett.<\/td>\n<td>8,0 BBL\/settimana<\/td>\n<td>10,0 BBL\/sett.<\/td>\n<\/tr>\n<tr>\n<td>35 giorni (birra lager)<\/td>\n<td>2,4 BBL\/settimana<\/td>\n<td>3,6 BBL\/settimana<\/td>\n<td>4,8 BBL\/settimana<\/td>\n<td>6,0 BBL\/sett.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>Ogni cifra = lotti\/settimana \u00d7 3 BBL. La manodopera necessaria per la produzione giornaliera rappresenta il limite pratico oltre i circa 4 lotti a settimana in un birrificio gestito da un unico operatore.<\/em><\/p>\n<h3><strong><b>Lo stesso sistema nell'intervallo 2\u20133,5 BBL<\/b><\/strong><\/h3>\n<p>Considerando un ciclo medio di 14 giorni e 48 settimane di produzione all\u2019anno:<\/p>\n<table style=\"height: 282px;\" width=\"1318\">\n<tbody>\n<tr>\n<td><strong><b>Sistema<\/b><\/strong><\/td>\n<td><strong><b>4 FV all'anno<\/b><\/strong><\/td>\n<td><strong><b>6 FV all'anno<\/b><\/strong><\/td>\n<td><strong><b>8 FV all'anno<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>2 BBL<\/td>\n<td>192 BBL<\/td>\n<td>288 BBL<\/td>\n<td>384 BBL<\/td>\n<\/tr>\n<tr>\n<td>2,5 BBL<\/td>\n<td>240 BBL<\/td>\n<td>360 BBL<\/td>\n<td>480 BBL<\/td>\n<\/tr>\n<tr>\n<td>3 BBL<\/td>\n<td>288 BBL<\/td>\n<td>432 BBL<\/td>\n<td>576 BBL<\/td>\n<\/tr>\n<tr>\n<td>3,5 BBL<\/td>\n<td>336 BBL<\/td>\n<td>504 BBL<\/td>\n<td>672 BBL<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Leggete queste due tabelle in relazione alla domanda piuttosto che a confronto l\u2019una con l\u2019altra. Un taproom da 60 posti che serve 1.000 pinte a settimana necessita di 473 L, circa 4 BBL. Un locale da 90 posti con un'intensa attivit\u00e0 nel fine settimana consuma 8\u201310 BBL a settimana. Il primo \u00e8 servito da 3 BBL con quattro fermentatori; il secondo ne richiede da sei a otto, e un impianto da 2 BBL non \u00e8 in grado di soddisfarne il fabbisogno con nessun numero di fermentatori che si adatti allo spazio disponibile.<\/p>\n<p>Effettua il calcolo a ritroso per il tuo progetto: dividi il BBL settimanale previsto per la dimensione di ogni lotto per ottenere il numero di lotti settimanali, moltiplica per i tuoi tempi di rotazione realistici, poi dividi per sette. Questo \u00e8 il numero di fermentatori di cui hai bisogno. Ordina quel numero di fermentatori, oppure prevedi le tubazioni e i canali di controllo necessari per poterli aggiungere in seguito.<\/p>\n<h2><strong><b>Carichi di servizio che \u00e8 possibile calcolare fin da subito<\/b><\/strong><\/h2>\n<p>Questi dati determinano il buon funzionamento di un edificio e devono essere forniti prima di qualsiasi sopralluogo.<\/p>\n<p><strong>Dimensioni dei bollitori elettrici.<\/strong>\u00a0Energia necessaria per portare il mosto dalla fase di mash-out all'ebollizione:<\/p>\n<p>kWh = (litri \u00d7 4,186 \u00d7 \u0394T \u00b0C) \u00f7 3.600<\/p>\n<p>Per 352 L con un aumento di temperatura di 30 \u00b0C dal momento del mash-out all'inizio dell'ebollizione: 12,3 kWh. Distribuiti su 45 minuti, ci\u00f2 corrisponde a un assorbimento della resistenza di 16 kW. Il mantenimento dell'ebollizione richiede un calcolo a parte, determinato dall'evaporazione piuttosto che dalla temperatura:<\/p>\n<p>kW necessari per mantenere l'ebollizione = (litri \u00d7 tasso di evaporazione \u00d7 2.257 kJ\/L) \u00f7 3.600<\/p>\n<p>Con un tasso di evaporazione di 71 TP3T all\u2019ora, un lotto da 3 BBL evapora 25 L all\u2019ora, richiedendo circa 15,5 kW in continuo. Se si considera anche il riscaldamento dell\u2019HLT, un impianto di produzione elettrico da 3 BBL richiede solitamente una potenza trifase compresa tra 30 e 40 kW. Controllate il quadro elettrico prima di verificare il vostro budget: garantire tale alimentazione in un locale commerciale in affitto \u00e8 spesso la parte pi\u00f9 difficile dell\u2019allestimento di un nano-birrificio o di un birrificio su piccola scala.<\/p>\n<p><strong>Carico di glicole.<\/strong>\u00a0\u00c8 il picco di carico, e non il carico medio, a determinare le dimensioni del refrigeratore. Il picco si verifica solitamente quando un fermentatore disperde il calore di fermentazione mentre un secondo viene raffreddato rapidamente.<\/p>\n<p>Potenza di raffreddamento in kW = (litri \u00d7 4,186 \u00d7 \u0394T) \u00f7 (ore \u00d7 3.600)<\/p>\n<p>Per raffreddare rapidamente 352 L da 20 \u00b0C a 2 \u00b0C in 24 ore occorrono 0,31 kW; in 12 ore, 0,61 kW. Aggiungere circa 0,3\u20130,5 kW per il funzionamento attivo <a href=\"https:\/\/cnbeerequipment.com\/it\/products\/serbatoi-di-fermentazione\/\">fermentazione<\/a> calcolo dell\u2019esotermia su un serbatoio parallelo, quindi aggiungere le perdite di linea e quelle ambientali, che risultano maggiori se il refrigeratore \u00e8 installato all\u2019aperto in estate. Il dimensionamento in base alla somma delle richieste simultanee realistiche, con un margine di sicurezza, \u00e8 ci\u00f2 che distingue un impianto in grado di mantenere una temperatura di 2 \u00b0C in agosto da uno che mantiene 6 \u00b0C e produce birra torbida e mal condizionata.<\/p>\n<p><strong>Acqua.<\/strong>\u00a0Prevedi un volume pari a 3\u20135 volte quello del lotto per ogni giornata di produzione, quindi 1.050\u20131.760 L per un lotto da 3 BBL, compresi l\u2019ammostatura, il lavaggio e la pulizia. L\u2019ammostatura e il lavaggio insieme rappresentano circa 1,5\u20131,7 volte il volume di lavoro, il che determina la dimensione minima dell\u2019HLT.<\/p>\n<p><strong>Cereali.<\/strong>\u00a0Con un OG di circa 1,050, un lotto da 352 L richiede all\u2019incirca 65\u201370 kg di malto, considerando l\u2019efficienza tipica dei piccoli impianti. Ci\u00f2 rappresenta uno dei limiti meno discussi in termini di dimensioni, di cui parleremo in seguito.<\/p>\n<h2><strong><b>Il limite di alta densit\u00e0 che nessuno menziona<\/b><\/strong><\/h2>\n<p>Una vasca di ammostamento\/filtrazione da 3 BBL, con un volume totale di 440 L, \u00e8 in grado di gestire agevolmente una quantit\u00e0 di cereali pari a 68 kg con un rapporto liquido\/cereali di 2,8 L\/kg: circa 190 L di acqua di ammostamento pi\u00f9 46 L di acqua di dislocamento dei cereali, ben all\u2019interno del recipiente.<\/p>\n<p>Raddoppiando la densit\u00e0 a 1,100, la quantit\u00e0 di malto sale a circa 135 kg. L'acqua di ammostamento, calcolata con lo stesso rapporto, \u00e8 di 378 L, il volume di malto \u00e8 di 90 L e l'ammostamento richiede 468 L in un recipiente dalla capacit\u00e0 di 440 L. L'impianto non \u00e8 in grado di effettuare l'ammostamento della birra in un unico recipiente.<\/p>\n<p>Tutte queste soluzioni alternative hanno un costo: ridurre il rapporto di ammostamento verso i 2,2 L\/kg e accettare una conversione inferiore e una filtrazione pi\u00f9 difficile, suddividere l\u2019ammostamento in due cicli e raddoppiare la durata della giornata di produzione, oppure aggiungere zucchero da birrificazione nel bollitore e modificare il profilo della birra. Chiunque abbia una linea di prodotti incentrata su imperial stout, barleywine o triple dovrebbe dimensionare il tino di ammostamento in base alla ricetta pi\u00f9 densa piuttosto che alla capacit\u00e0 nominale dell\u2019impianto, il che in pratica significa un tino di ammostamento\/filtrazione di una taglia superiore rispetto al bollitore.<\/p>\n<p>Questo \u00e8 l'errore nelle specifiche che si riscontra pi\u00f9 spesso dopo l'installazione, poich\u00e9 la capacit\u00e0 del sistema viene pubblicizzata sulla base di un'ipotesi di gravit\u00e0 standard che nessun fornitore specifica.<\/p>\n<h2><strong><b>2 vasi contro 3 vasi su questa scala<\/b><\/strong><\/h2>\n<table style=\"height: 422px;\" width=\"1283\">\n<tbody>\n<tr>\n<td><strong><b>\u00a0<\/b><\/strong><\/td>\n<td><strong><b>A 2 vasi<\/b><\/strong><\/td>\n<td><strong><b>A 3 vasi<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>Superficie (3 BBL)<\/td>\n<td>1,8\u20132,2 m\u00b2<\/td>\n<td>2,6\u20133,1 m\u00b2<\/td>\n<\/tr>\n<tr>\n<td>Giorno di produzione, un lotto<\/td>\n<td>5\u20137 ore<\/td>\n<td>5\u20137 ore<\/td>\n<\/tr>\n<tr>\n<td>Due lotti, un turno<\/td>\n<td>Il bollitore deve essere svuotato prima del secondo filtraggio<\/td>\n<td>Pratico, con vasca idromassaggio dedicata<\/td>\n<\/tr>\n<tr>\n<td>Acqua di lavaggio<\/td>\n<td>\u00c8 necessario un sistema HLT separato o un sistema di riscaldamento a richiesta<\/td>\n<td>HLT integrato<\/td>\n<\/tr>\n<tr>\n<td>\u00c8 il momento decisivo<\/td>\n<td>Pi\u00f9 a lungo; riposo nell'idromassaggio nel bollitore<\/td>\n<td>Pi\u00f9 veloce; idromassaggio dedicato<\/td>\n<\/tr>\n<tr>\n<td>Movimentazione di materiali ad alta densit\u00e0<\/td>\n<td>In conformit\u00e0 con quanto indicato nella sezione precedente<\/td>\n<td>Meglio ancora, se il recipiente aggiunto \u00e8 il tino di ammostamento<\/td>\n<\/tr>\n<tr>\n<td>Costo di capitale<\/td>\n<td>Inferiore<\/td>\n<td>Pi\u00f9 alto<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Per un unico lotto al giorno di produzione, come avviene nella maggior parte dei brewpub di queste dimensioni, un impianto a due serbatoi \u00e8 solitamente sufficiente, ed \u00e8 meglio investire il denaro in fermentatori aggiuntivi. Il terzo serbatoio diventa necessario quando si producono due lotti per turno o quando le birre ad alta densit\u00e0 diventano una pratica abituale.<\/p>\n<figure id=\"attachment_3845\" aria-describedby=\"caption-attachment-3845\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-3845 size-full\" src=\"https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/07\/Microbrewery-Equipment-3.webp\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/07\/Microbrewery-Equipment-3.webp 600w, https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/07\/Microbrewery-Equipment-3-300x200.webp 300w, https:\/\/cnbeerequipment.com\/wp-content\/uploads\/2026\/07\/Microbrewery-Equipment-3-18x12.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-3845\" class=\"wp-caption-text\">Sistema di produzione 3 BBL: specifiche tecniche, ingombro e calcolo dei lotti<\/figcaption><\/figure>\n<h2><strong><b>Sistemi ZPET 3 BBL: scheda tecnica<\/b><\/strong><\/h2>\n<p>I nostri impianti da 2\u20133,5 BBL rientrano nella categoria <a href=\"https:\/\/cnbeerequipment.com\/it\/products\/attrezzature-per-nanobirrifici\/\">Attrezzature per il nano-birrificio<\/a> linea, realizzata sulla <a href=\"https:\/\/cnbeerequipment.com\/it\/products\/impianti-di-produzione-della-birra\/\">Sistemi per la produzione di birra<\/a> piattaforma in configurazione a 2 o 3 serbatoi.<\/p>\n<table style=\"height: 988px;\" width=\"1320\">\n<tbody>\n<tr>\n<td><strong><b>Parametro<\/b><\/strong><\/td>\n<td><strong><b>Specifiche<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>Fascia di capacit\u00e0<\/td>\n<td>117\u2013587 L (1\u20135 BBL); questo articolo tratta il periodo compreso tra 235 e 411 L (2\u20133,5 BBL)<\/td>\n<\/tr>\n<tr>\n<td>Configurazioni degli impianti di produzione della birra<\/td>\n<td>Disponibili configurazioni da 2 a 5 serbatoi; in genere, a questa scala si utilizzano configurazioni a 2 o 3 serbatoi<\/td>\n<\/tr>\n<tr>\n<td>Riscaldamento<\/td>\n<td>A vapore \/ elettrico \/ a fuoco diretto<\/td>\n<\/tr>\n<tr>\n<td>Materiali<\/td>\n<td>SS304 o SS316L, qualit\u00e0 sanitaria<\/td>\n<\/tr>\n<tr>\n<td>Finitura delle superfici interne<\/td>\n<td>Lucidatura a specchio da 0,4 \u03bcm<\/td>\n<\/tr>\n<tr>\n<td>Raffreddamento del fermentatore<\/td>\n<td>Camicia di raffreddamento a fossette<\/td>\n<\/tr>\n<tr>\n<td>Accesso al serbatoio<\/td>\n<td>Passaggio superiore di serie; passaggio laterale opzionale<\/td>\n<\/tr>\n<tr>\n<td>Saldatura<\/td>\n<td>TIG \/ saldatura ad arco con argon su entrambi i lati; robot di saldatura automatici; lamiera tagliata al laser con controllo numerico (CNC)<\/td>\n<\/tr>\n<tr>\n<td>Controllo delle merci in entrata<\/td>\n<td>Analisi spettrometrica sull'acciaio inossidabile<\/td>\n<\/tr>\n<tr>\n<td>Prove di pressione<\/td>\n<td>Prova di mantenimento della pressione per 24 ore<\/td>\n<\/tr>\n<tr>\n<td>Ispezione delle saldature<\/td>\n<td>Ispezione delle saldature mediante raggi X; sequenza di controllo qualit\u00e0 in 5 fasi<\/td>\n<\/tr>\n<tr>\n<td>Controllo della temperatura<\/td>\n<td>Controllo di precisione dell'impianto di birrificazione e della fermentazione per zona<\/td>\n<\/tr>\n<tr>\n<td>Piattaforma operativa<\/td>\n<td>Piattaforma ergonomica progettata in base all'altezza dell'imbarcazione<\/td>\n<\/tr>\n<tr>\n<td>Garanzia strutturale<\/td>\n<td>10 anni<\/td>\n<\/tr>\n<tr>\n<td>Conformit\u00e0 alle norme sull'esportazione<\/td>\n<td>Progettato per soddisfare i requisiti PED (CE), UL\/cUL e AS1210<\/td>\n<\/tr>\n<tr>\n<td>Consegna del prodotto in preordine<\/td>\n<td>Planimetria 3D del birrificio, disegni tecnici e diagramma di flusso del processo<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Tre appunti su quel tavolo.<\/p>\n<p>La finitura interna di 0,4 \u03bcm \u00e8 una specifica di rugosit\u00e0, la stessa propriet\u00e0 che la norma ASME BPE considera nelle sue designazioni relative alle finiture superficiali igieniche, ed \u00e8 il parametro che determina se la pulizia in loco rimuove lo sporco o si limita a bagnarlo. Richiedetela in \u03bcm Ra anzich\u00e9 come denominazione del grado di lucidatura, poich\u00e9 la nomenclatura dei gradi varia da un produttore all\u2019altro.<\/p>\n<p>&#8220;Engineered to meet PED (CE), UL\/cUL and AS1210&#8221; is precise wording and worth understanding. It means vessels and control panels are designed against the requirements of those standards. It is a different statement from holding a third-party certificate for a specific unit. Any supplier should be able to tell you which of the two they are offering, and should be able to show you the document.<\/p>\n<p>Le dimensioni dei serbatoi vengono stabilite in base all\u2019ordine e non sono fissate in catalogo, poich\u00e9 a questo livello la progettazione viene adattata all\u2019edificio. Prima di avviare la produzione, realizziamo il progetto 3D sulla base della planimetria misurata dal cliente, delle posizioni degli scarichi, degli ostacoli presenti sul soffitto e dell\u2019impianto elettrico disponibile; questo ci permette di evitare che venga consegnato un serbatoio che non possa entrare nella stanza o che non possa essere posizionato al di sotto della linea degli sprinkler.<\/p>\n<p>Rispetto ai serbatoi di seconda mano provenienti dall\u2019industria lattiero-casearia e alimentare, spesso presentati come una soluzione a basso costo per questa fascia di capacit\u00e0, i serbatoi appositamente progettati per la produzione di birra si distinguono per quattro aspetti specifici: una copertura della camicia dimensionata in base al carico termico della fermentazione piuttosto che alla conservazione del prodotto, una geometria del fondo conico per la raccolta del lievito, una pressione nominale che consente lo spunding e la carbonatazione naturale, e la tracciabilit\u00e0 documentata dei materiali. I serbatoi riconvertiti sono pi\u00f9 economici al litro. Il birrificio realizzato con essi, in genere, non lo \u00e8.<\/p>\n<h2><strong><b>Domande frequenti<\/b><\/strong><\/h2>\n<h3><strong>D: Quanti fusti si ottengono da un lotto da 3 BBL?<\/strong><\/h3>\n<p>A: Sei fusti da mezzo barile statunitensi da 352 L, al lordo delle perdite. Considerare 5,5 fusti come quantit\u00e0 realistica al netto delle perdite dovute a sedimenti, lievito e travaso, pari a 5\u201310%.<\/p>\n<h3><strong>D: Quanto spazio a pavimento occorre per un impianto di produzione di birra da 3 BBL?<\/strong><\/h3>\n<p>A: I serbatoi del reparto di produzione occupano circa 2 m\u00b2. Un birrificio operativo dotato di sei fermentatori, sistema a glicole, CIP, impianto di movimentazione del malto e logistica dei fusti richiede 45\u201360 m\u00b2 (485\u2013645 ft\u00b2), oltre allo spazio dedicato al confezionamento, se previsto.<\/p>\n<h3><strong>D: Qual \u00e8 l'altezza del soffitto necessaria per un impianto da 3 BBL?<\/strong><\/h3>\n<p>A: 3,0 m come minimo, 3,4 m per un maggiore comfort. I fermentatori di queste dimensioni raggiungono un\u2019altezza complessiva di 2,0\u20132,3 m ed \u00e8 necessario garantire uno spazio libero sopra il passaggio di ispezione superiore. Misurare fino all\u2019ostacolo pi\u00f9 basso, compresi gli irrigatori e i condotti, non fino alla soletta strutturale.<\/p>\n<h3><strong>D: 2 BBL o 3 BBL?<\/strong><\/h3>\n<p>R: 3 BBL nella maggior parte dei casi. Consente di ottenere 50% di birra in pi\u00f9 per ogni lotto a parit\u00e0 di manodopera giornaliera, con gli stessi spazi liberi e 6\u20139 m\u00b2 di spazio in pi\u00f9. L\u2019opzione da 2 BBL ha senso solo nei casi in cui lo spazio a disposizione non consenta effettivamente di ospitare un impianto pi\u00f9 grande o quando un singolo lotto da 235 L sia adeguato a un programma di spillatura volutamente ridotto e ad alta rotazione.<\/p>\n<h3><strong>D: Di quanta energia elettrica ha bisogno un impianto di produzione di birra elettrico da 3 BBL?<\/strong><\/h3>\n<p>A: Di solito 30\u201340 kW trifase tra bollitore e HLT. Il dimensionamento dell\u2019elemento riscaldante del bollitore dipende dal tempo di riscaldamento e dalla velocit\u00e0 di evaporazione: circa 16 kW per raggiungere l\u2019ebollizione in 45 minuti e circa 15,5 kW per mantenere un\u2019ebollizione di 71 TP3T\/ora su 352 L.<\/p>\n<h3><strong>D: \u00c8 possibile produrre birra ad alta densit\u00e0 con un impianto da 3 BBL?<\/strong><\/h3>\n<p>R: Non \u00e8 possibile raggiungere il volume totale del lotto con una densit\u00e0 iniziale (OG) superiore a circa 1,080 in un tino di ammostamento standard da 3 BBL, poich\u00e9 la quantit\u00e0 di cereali e l\u2019acqua di ammostamento superano il volume del recipiente. Le opzioni disponibili sono: un rapporto di ammostamento pi\u00f9 ridotto, un ammostamento frazionato, l\u2019aggiunta di zucchero nel bollitore oppure la richiesta, al momento dell\u2019ordine, di un tino di ammostamento\/filtrazione di dimensioni maggiori.<\/p>\n<h3><strong>D: Qual \u00e8 la differenza tra i sistemi da 3 BBL e quelli da 3,5 BBL?<\/strong><\/h3>\n<p>R: 59 litri, ovvero un fusto da mezzo barile in pi\u00f9 per ogni lotto. Il diametro del serbatoio aumenta di circa 5 cm e la superficie occupata di meno di 0,5 m\u00b2, quindi, se lo spazio lo consente, 3,5 BBL rappresentano in genere la scelta migliore in termini di produttivit\u00e0 per ingombro.<\/p>","protected":false},"excerpt":{"rendered":"<p>David Zhang | Founder &amp; CEO, ZPET (Shandong ZhongPi Machinery Equipment Co., Ltd.) | Published August , 2026 A 3 BBL brewing system handles 352 L per batch. Its brewhouse occupies roughly 2 m\u00b2, but the working brewery needs 45\u201360 m\u00b2 and 3 m of ceiling height. Weekly output is 6\u201313 BBL depending on fermenter [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new"],"_links":{"self":[{"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/posts\/3912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/comments?post=3912"}],"version-history":[{"count":2,"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/posts\/3912\/revisions"}],"predecessor-version":[{"id":3916,"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/posts\/3912\/revisions\/3916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/media\/3913"}],"wp:attachment":[{"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/media?parent=3912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/categories?post=3912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnbeerequipment.com\/it\/wp-json\/wp\/v2\/tags?post=3912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}